{"id":478,"date":"2008-08-16T06:45:21","date_gmt":"2008-08-16T06:45:21","guid":{"rendered":"http:\/\/www.foot-parier.com\/?p=478"},"modified":"2008-08-16T06:45:21","modified_gmt":"2008-08-16T06:45:21","slug":"paris-sg-bordeaux-4","status":"publish","type":"post","link":"https:\/\/www.foot-parier.com\/ar\/%d8%a8%d8%a7%d8%b1%d9%8a%d8%b3-%d8%b3%d8%a7%d9%86-%d8%ac%d8%b1%d9%85%d8%a7%d9%86-%d8%a8%d9%88%d8%b1%d8%af%d9%88-4\/","title":{"rendered":"Paris SG \u2013 Bordeaux"},"content":{"rendered":"<h3>\u0628\u0627\u0631\u064a\u0633 \u062a\u0646\u062a\u0638\u0631 \u0628\u0648\u0631\u062f\u0648<\/h3>\n<p>Comme la saison derni\u00e8re, Paris a rat\u00e9 sa rentr\u00e9e en Ligue 1. A Monaco (1-0), les joueurs de la capitale ont manqu\u00e9 de caract\u00e8re pour s&#8217;imposer. Face \u00e0 Bordeaux, l&#8217;objectif est d\u00e9j\u00e0 la victoire pour rester dans le coup au niveau comptable. Vainqueurs face \u00e0 Caen (2-1), les<br \/>\nGirondins se voient bien plomber l&#8217;ambiance au Parc des Princes. Choc \u00e0 l&#8217;affiche, pariez ! <\/p>\n<p>\u0627\u0644\u0627\u062d\u062a\u0645\u0627\u0644\u0627\u062a \u0639\u0644\u0649 Betclic<br \/>\n \u0628\u0627\u0631\u064a\u0633 SG 2.55 \u0631\u0633\u0645 3.00 \u0628\u0648\u0631\u062f\u0648 2.85 <\/p>","protected":false},"excerpt":{"rendered":"<p>Paris attend Bordeaux Comme la saison derni\u00e8re, Paris a rat\u00e9 sa rentr\u00e9e en Ligue 1&#8230;.<\/p>","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[30,261],"_links":{"self":[{"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/posts\/478"}],"collection":[{"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":1,"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/posts\/478\/revisions"}],"predecessor-version":[{"id":479,"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/posts\/478\/revisions\/479"}],"wp:attachment":[{"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/media?parent=478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/categories?post=478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foot-parier.com\/ar\/wp-json\/wp\/v2\/tags?post=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}