{"id":718,"date":"2008-10-05T21:00:05","date_gmt":"2008-10-05T21:00:05","guid":{"rendered":"http:\/\/www.foot-parier.com\/?p=718"},"modified":"2008-10-05T05:02:11","modified_gmt":"2008-10-05T05:02:11","slug":"nancy-paris-sg","status":"publish","type":"post","link":"https:\/\/www.foot-parier.com\/cs\/nancy-paris-sg\/","title":{"rendered":"Nancy \u2013 Pa\u0159\u00ed\u017e-SG"},"content":{"rendered":"<h3>Mus\u00edte sk\u00f3rovat!<\/h3>\n<p>Malgr\u00e9 une qualification pour le prochain tour de la Coupe de l&#8217;UEFA, Paris est en manque d&#8217;inspiration depuis plusieurs journ\u00e9es. Les parisiens devront \u00e0 tout prix compenser leurs carences offensives s&#8217;ils veulent s&#8217;imposer sur le terrain de Nancy. Les deux \u00e9quipes, aux premi\u00e8res places du classement des moins bonnes attaques de Ligue 1, retrouveront-elles du r\u00e9alisme pour avoir l&#8217;espoir de remporter ce match ?<\/p>\n<p>Kurzy na Betclic<br \/>\nNancy 2.45 Losov\u00e1n\u00ed 3.00 Paris SG 3.00<\/p>","protected":false},"excerpt":{"rendered":"<p>Mus\u00edte sk\u00f3rovat! Navzdory kvalifikaci do dal\u0161\u00edho kola Coupe de\u2026<\/p>","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[60,261],"_links":{"self":[{"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/posts\/718"}],"collection":[{"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/comments?post=718"}],"version-history":[{"count":2,"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/posts\/718\/revisions"}],"predecessor-version":[{"id":899,"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/posts\/718\/revisions\/899"}],"wp:attachment":[{"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/media?parent=718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/categories?post=718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foot-parier.com\/cs\/wp-json\/wp\/v2\/tags?post=718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}