{"id":261,"date":"2008-03-23T20:55:19","date_gmt":"2008-03-23T20:55:19","guid":{"rendered":"http:\/\/www.foot-parier.com\/lyon-paris-sg\/"},"modified":"2008-03-22T05:51:48","modified_gmt":"2008-03-22T05:51:48","slug":"lyon-paris-sg","status":"publish","type":"post","link":"https:\/\/www.foot-parier.com\/es\/lyon-paris-sg\/","title":{"rendered":"Lyon-Par\u00eds SG"},"content":{"rendered":"<p>Paris SG, 17\u00ba en la Ligue 1, est\u00e1 casi en la misma posici\u00f3n que hace un a\u00f1o. En el mismo tramo de la competici\u00f3n, hab\u00eda vencido al Lens (2-1) y se relanzaba hacia la senda del mantenimiento. Pero esta vez es Lyon, en busca de una s\u00e9ptima coronaci\u00f3n, la que se interpone en el camino de los habitantes de Ile-de-France. Des Gones, que tiene m\u00e1s confianza despu\u00e9s de 2 \u00e9xitos consecutivos y todav\u00eda bajo la amenaza de Burdeos. Baste decir que este shock promete mucho\u2026<\/p>\n<p>Cuotas en Betclic<\/p>\n<p>Lyon 1,45 Empate 4,00 Par\u00eds SG 7,00<\/p>","protected":false},"excerpt":{"rendered":"<p>Paris SG, 17\u00ba en Ligue 1, est\u00e1 casi en la misma posici\u00f3n que all\u00ed\u2026<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[63,261],"_links":{"self":[{"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/posts\/261"}],"collection":[{"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":0,"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/posts\/261\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/media?parent=261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/categories?post=261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foot-parier.com\/es\/wp-json\/wp\/v2\/tags?post=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}