{"id":1157,"date":"2022-02-06T19:45:00","date_gmt":"2022-02-06T19:45:00","guid":{"rendered":"https:\/\/www.foot-parier.com\/?p=1157"},"modified":"2022-02-09T07:19:45","modified_gmt":"2022-02-09T07:19:45","slug":"lille-paris","status":"publish","type":"post","link":"https:\/\/www.foot-parier.com\/nl\/rijsel-parijs\/","title":{"rendered":"Rijsel-Parijs"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.foot-parier.com\/wp-content\/uploads\/2022\/02\/lile-psg.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/www.foot-parier.com\/wp-content\/uploads\/2022\/02\/lile-psg-1024x576.jpg\" alt=\"\" class=\"wp-image-1173\" srcset=\"https:\/\/www.foot-parier.com\/wp-content\/uploads\/2022\/02\/lile-psg-1024x576.jpg 1024w, https:\/\/www.foot-parier.com\/wp-content\/uploads\/2022\/02\/lile-psg-300x169.jpg 300w, https:\/\/www.foot-parier.com\/wp-content\/uploads\/2022\/02\/lile-psg-768x432.jpg 768w, https:\/\/www.foot-parier.com\/wp-content\/uploads\/2022\/02\/lile-psg.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"le-match-de-la-saison-derniere-a-confirme-que-lille-pourrait-enfin-mettre-fin-au-mandat-du-paris-saint-germain-en-tant-que-champion-de-ligue-1-et-soulever-le-trophee\">De wedstrijd van vorig seizoen bevestigde dat Lille eindelijk een einde kon maken aan de ambtstermijn van Paris Saint-Germain als Ligue 1-kampioen en de trofee in de wacht kon slepen.<\/h3>\n\n\n\n<p>Les choses ont bien chang\u00e9 en France lorsque les deux \u00e9quipes se sont rencontr\u00e9es au stade Pierre Moroy ce Super dimanche. Lille, d\u00e9tenteur de la Ligue 1, n&#8217;est pas seulement tomb\u00e9 dans le top quatre, mais aussi de la premi\u00e8re moiti\u00e9 du classement. LOSC a perdu six de ses 22 matchs cette saison, cinq de plus que le <a href=\"https:\/\/www.foot-parier.com\/nl\/equipe\/paris-saint-germain\/\" data-internallinksmanager029f6b8e52c=\"3\" title=\"PSG\">Paris Saint-Germain<\/a>, apr\u00e8s avoir perdu contre Brest lors de son dernier match \u00e0 l&#8217;ext\u00e9rieur.<strong> Ondertussen zijn de Parijzenaars terug in hun beste vorm met 16 overwinningen uit 22 wedstrijden dit seizoen.<\/strong> <\/p>\n\n\n\n<p>Lille n&#8217;est peut-\u00eatre pas en lice pour une place europ\u00e9enne cette saison, mais ils sont en tr\u00e8s bonne forme \u00e0 domicile. Les champions en titre n&#8217;ont remport\u00e9 qu&#8217;un seul match \u00e0 domicile depuis le d\u00e9but de la saison. Cela est devenu un fait indispensable puisque le Paris Saint-Germain est entr\u00e9 dans le match avec un pourcentage de victoires \u00e0 l&#8217;ext\u00e9rieur inf\u00e9rieur \u00e0 60 %.  Ajoutez \u00e0 cela que Lille a marqu\u00e9 dans 5 de ses 6 derniers matchs et nous pourrions avoir un festin de buts fantastique dimanche. Un nombre tr\u00e8s inhabituel de buts observ\u00e9s dans ce match a \u00e9t\u00e9 inf\u00e9rieur \u00e0 2,5 buts lors de cinq des sept derniers matchs, et nous pensons que cela pourrait changer ce week-end. <\/p>\n\n\n\n<p>Le Paris Saint-Germain sera certainement avide de trois points (et vengeur la saison derni\u00e8re) de son expulsion de la Coupe de France aux mains de l&#8217;OGC Nice. <\/p>","protected":false},"excerpt":{"rendered":"<p>De wedstrijd van vorig seizoen bevestigde dat Lille eindelijk een einde kon maken aan de\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[68,261],"_links":{"self":[{"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/posts\/1157"}],"collection":[{"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":2,"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/posts\/1157\/revisions"}],"predecessor-version":[{"id":1174,"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/posts\/1157\/revisions\/1174"}],"wp:attachment":[{"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/categories?post=1157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foot-parier.com\/nl\/wp-json\/wp\/v2\/tags?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}